{"id":30254,"date":"2026-05-05T16:52:45","date_gmt":"2026-05-05T14:52:45","guid":{"rendered":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere"},"modified":"2026-05-13T09:45:15","modified_gmt":"2026-05-13T07:45:15","slug":"starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere","status":"publish","type":"job","link":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere","title":{"rendered":"CNC-Dreher (m\/w\/d)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-30254","job","type-job","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CNC-Dreher (m\/w\/d) - Trummer Austria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNC-Dreher (m\/w\/d) - Trummer Austria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere\" \/>\n<meta property=\"og:site_name\" content=\"Trummer Austria\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T07:45:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere\",\"url\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere\",\"name\":\"CNC-Dreher (m\\\/w\\\/d) - Trummer Austria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/#website\"},\"datePublished\":\"2026-05-05T14:52:45+00:00\",\"dateModified\":\"2026-05-13T07:45:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/trummer.eu\\\/at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNC-Dreher (m\\\/w\\\/d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/#website\",\"url\":\"https:\\\/\\\/trummer.eu\\\/at\\\/\",\"name\":\"Trummer Austria\",\"description\":\"Trummer | Die besten Jobs seit 1987.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trummer.eu\\\/at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CNC-Dreher (m\/w\/d) - Trummer Austria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere","og_locale":"de_DE","og_type":"article","og_title":"CNC-Dreher (m\/w\/d) - Trummer Austria","og_url":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere","og_site_name":"Trummer Austria","article_modified_time":"2026-05-13T07:45:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere","url":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere","name":"CNC-Dreher (m\/w\/d) - Trummer Austria","isPartOf":{"@id":"https:\/\/trummer.eu\/at\/#website"},"datePublished":"2026-05-05T14:52:45+00:00","dateModified":"2026-05-13T07:45:15+00:00","breadcrumb":{"@id":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/trummer.eu\/at\/jobs\/starte-jetzt-als-cnc-dreher-m-w-d-praezision-trifft-karriere#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/trummer.eu\/at\/"},{"@type":"ListItem","position":2,"name":"CNC-Dreher (m\/w\/d)"}]},{"@type":"WebSite","@id":"https:\/\/trummer.eu\/at\/#website","url":"https:\/\/trummer.eu\/at\/","name":"Trummer Austria","description":"Trummer | Die besten Jobs seit 1987.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trummer.eu\/at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/job\/30254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/media?parent=30254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}