{"id":30256,"date":"2026-05-05T16:52:46","date_gmt":"2026-05-05T14:52:46","guid":{"rendered":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns"},"modified":"2026-05-13T10:30:19","modified_gmt":"2026-05-13T08:30:19","slug":"vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns","status":"publish","type":"job","link":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns","title":{"rendered":"Vorarbeiter (m\/w\/d) Hochbau"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-30256","job","type-job","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vorarbeiter (m\/w\/d) Hochbau - Trummer Austria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorarbeiter (m\/w\/d) Hochbau - Trummer Austria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns\" \/>\n<meta property=\"og:site_name\" content=\"Trummer Austria\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:30:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns\",\"url\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns\",\"name\":\"Vorarbeiter (m\\\/w\\\/d) Hochbau - Trummer Austria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/#website\"},\"datePublished\":\"2026-05-05T14:52:46+00:00\",\"dateModified\":\"2026-05-13T08:30:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/trummer.eu\\\/at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorarbeiter (m\\\/w\\\/d) Hochbau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/#website\",\"url\":\"https:\\\/\\\/trummer.eu\\\/at\\\/\",\"name\":\"Trummer Austria\",\"description\":\"Trummer | Die besten Jobs seit 1987.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trummer.eu\\\/at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorarbeiter (m\/w\/d) Hochbau - Trummer Austria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns","og_locale":"de_DE","og_type":"article","og_title":"Vorarbeiter (m\/w\/d) Hochbau - Trummer Austria","og_url":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns","og_site_name":"Trummer Austria","article_modified_time":"2026-05-13T08:30:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns","url":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns","name":"Vorarbeiter (m\/w\/d) Hochbau - Trummer Austria","isPartOf":{"@id":"https:\/\/trummer.eu\/at\/#website"},"datePublished":"2026-05-05T14:52:46+00:00","dateModified":"2026-05-13T08:30:19+00:00","breadcrumb":{"@id":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/trummer.eu\/at\/jobs\/vorarbeiter-m-w-d-hochbau-gestalten-sie-bauprojekte-mit-uns#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/trummer.eu\/at\/"},{"@type":"ListItem","position":2,"name":"Vorarbeiter (m\/w\/d) Hochbau"}]},{"@type":"WebSite","@id":"https:\/\/trummer.eu\/at\/#website","url":"https:\/\/trummer.eu\/at\/","name":"Trummer Austria","description":"Trummer | Die besten Jobs seit 1987.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trummer.eu\/at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/job\/30256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/media?parent=30256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}