{"id":30345,"date":"2026-05-05T16:53:00","date_gmt":"2026-05-05T14:53:00","guid":{"rendered":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft"},"modified":"2026-05-13T12:45:14","modified_gmt":"2026-05-13T10:45:14","slug":"werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft","status":"publish","type":"job","link":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft","title":{"rendered":"Dachdecker (m\/w\/d)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-30345","job","type-job","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dachdecker (m\/w\/d) - Trummer Austria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dachdecker (m\/w\/d) - Trummer Austria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft\" \/>\n<meta property=\"og:site_name\" content=\"Trummer Austria\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:45:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft\",\"url\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft\",\"name\":\"Dachdecker (m\\\/w\\\/d) - Trummer Austria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/#website\"},\"datePublished\":\"2026-05-05T14:53:00+00:00\",\"dateModified\":\"2026-05-13T10:45:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/jobs\\\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/trummer.eu\\\/at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dachdecker (m\\\/w\\\/d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trummer.eu\\\/at\\\/#website\",\"url\":\"https:\\\/\\\/trummer.eu\\\/at\\\/\",\"name\":\"Trummer Austria\",\"description\":\"Trummer | Die besten Jobs seit 1987.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trummer.eu\\\/at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dachdecker (m\/w\/d) - Trummer Austria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft","og_locale":"de_DE","og_type":"article","og_title":"Dachdecker (m\/w\/d) - Trummer Austria","og_url":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft","og_site_name":"Trummer Austria","article_modified_time":"2026-05-13T10:45:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft","url":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft","name":"Dachdecker (m\/w\/d) - Trummer Austria","isPartOf":{"@id":"https:\/\/trummer.eu\/at\/#website"},"datePublished":"2026-05-05T14:53:00+00:00","dateModified":"2026-05-13T10:45:14+00:00","breadcrumb":{"@id":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/trummer.eu\/at\/jobs\/werde-dachdecker-m-w-d-in-klagenfurt-gestalte-daecher-sichere-zukunft#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/trummer.eu\/at\/"},{"@type":"ListItem","position":2,"name":"Dachdecker (m\/w\/d)"}]},{"@type":"WebSite","@id":"https:\/\/trummer.eu\/at\/#website","url":"https:\/\/trummer.eu\/at\/","name":"Trummer Austria","description":"Trummer | Die besten Jobs seit 1987.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trummer.eu\/at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/job\/30345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/trummer.eu\/at\/wp-json\/wp\/v2\/media?parent=30345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}